{"id":104232,"date":"2014-03-11T17:30:46","date_gmt":"2014-03-11T17:30:46","guid":{"rendered":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/?p=104232"},"modified":"2025-03-14T14:02:04","modified_gmt":"2025-03-14T12:02:04","slug":"leicht-und-lesbar","status":"publish","type":"post","link":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/leicht-und-lesbar-10104232\/","title":{"rendered":"Leicht und lesbar"},"content":{"rendered":"<p><figure class=\"hammy-responsive attachment alighnleft alignleft\" title=\"Die Ink Paper Watch hat ein besonders flaches Geh\u00e4use\"  data-media=\"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-content\/uploads\/2014\/03\/213687-150x150.jpg\"><noscript><img src=\"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-content\/uploads\/2014\/03\/213687-150x150.jpg\" alt=\"Die Ink Paper Watch hat ein besonders flaches Geh\u00e4use\" title=\"Die Ink Paper Watch hat ein besonders flaches Geh\u00e4use\" width=\"119\" height=\"119\"><\/noscript><\/figure>Da wird Mann schwach &#8211; Neue Kollektion von Designeruhren der Marke DETAMOSO. Besonderes Highlight: Die Ink Paper Watch. Die hochmoderne Technik verbirgt in einem edlen Geh\u00e4use mit dem typischen roten Armband an der Innenseite einen besonderen Clou &#8211; Sie ist ausgestattet mit einer indirekten Displaybeleuchtung, wie sie bereits bei modernen eBook-Readern eingesetzt wird.<\/p>\n<div><!--more-->Pr\u00e4zision schwarz auf wei\u00df<\/div>\n<p>Inchiostro: DETOMASO stellt digitale Ink Paper Watch mit extra flachem Display vor<br \/>\nMonheim, 11. M\u00e4rz 2014. Schlichtes Design, innovative Darstellung: So zeigt sich die Inchiostro von DETOMASO. Die modische Herrenuhr im hochmodernen Ink Paper-Stil setzt auf eine vergleichbare indirekte Display-Beleuchtung wie sie bereits namhafte Hersteller von eBook-Readern nutzen. Hierbei wird Licht \u00e4hnlich wie auf herk\u00f6mmlichem Papier reflektiert. Das macht die Anzeige auch bei Sonneneinstrahlung gut erkennbar und besonders lesefreundlich. Wahlweise kann die Anzeige auf wei\u00dfe Schrift mit schwarzem Hintergrund oder schwarzer Anzeige auf wei\u00dfem Grund eingestellt werden. Mit dieser innovativen Technologie spricht die Inchiostro Ink Paper Watch von DETOMASO besonders stilbewusste und Technik-affine M\u00e4nner an.<\/p>\n<p>Leichtgewicht mit Tragekomfort<\/p>\n<p>Gleichzeitig setzt die Inchiostro auf besonders hohen Tragekomfort. Daf\u00fcr sorgt das mit elf Millimetern besonders flache Geh\u00e4use sowie das schwarze Lederarmband, das sich angenehm ans Handgelenk schmiegt und stilsicher zu jedem Outfit kombiniert wird. Dabei ist die DETOMASO-Uhr ein echtes Leicht-gewicht: Mit gerade einmal 63 Gramm wiegt sie in etwa so viel, wie ein hochwertig verarbeiteter Kugelschreiber. Diese minimalistischen Features gepaart mit innovativer Technologie machen die Inchiostro einzigartig, auch im Vergleich zu anderen Modellen der DETOMASO-Kollektionen. Dar\u00fcber hinaus bietet die Ink Paper Watch gewohnte DETOMASO-Qualit\u00e4tsmerkmale und punktet mit einem robusten Geh\u00e4use aus Edelstahl, kratzfestem Mineralglas und hochwertigem Quarz-Uhrwerk. Charakteristisch bleibt die DETOMASO-typische, rote Innenseite des Armbands.<\/p>\n<p>Alle Uhren werden in edlen Metallboxen geliefert und sind somit auch ein sch\u00f6nes Geschenk. Erh\u00e4ltlich sind die DETOMASO-Modelle in ausgesuchten Onlineshops &#8211; wie beispielsweise Amazon.de oder Maxtrader.de &#8211; mit 24-monatiger Hersteller-Garantie. Unverbindliche Preisempfehlung des Herstellers: 215 Euro. Weitere Infos: www.detomaso-watches.de<\/p>\n<p>&nbsp;<\/p>\n<p>Bildquelle:kein externes Copyright<\/p>\n<p>DETOMASO<br \/>\nDesign trifft Funktion: Bereits seit 1993 entwickelt DETOMASO elegante und hochwertige Uhren f\u00fcr Sport, Business und Alltag. Dabei setzt das Unternehmen aus Monheim auf trendorientiertes Design, h\u00f6chste Qualit\u00e4t und ein hervorragendes Preis-Leistungs-Verh\u00e4ltnis. In den drei Kollektionen Classic, Trend und Ladies bietet DETOMASO mehr als 100 Modelle in Trendfarben sowie schlichtem und modischen Design. Zu den ausgew\u00e4hlten Materialien &#8211; wie Keramik, Saphir- und Kristallglas sowie Edelstahl &#8211; verbaut DETOMASO Uhrwerke der Traditionsmarken Seiko Instruments und Citizen Miyota. Die Uhren sind in ausgesuchten Online-Shops erh\u00e4ltlich, wie beispielsweise Amazon.de oder Maxtrader.de. Sie werden in einer hochwertigen Geschenkverpackung geliefert und stehen unter einem 24-monatigen Garantieversprechen. Weitere Informationen unter: www.detomaso-watches.de und www.facebook.com\/DetomasoWatches<\/p>\n<p>Temporex Uhrenhandel GmbH<br \/>\nPetra Herbst<br \/>\nStorchenweg 3<br \/>\n40789 Monheim<br \/>\n0700 \/ 83676739<br \/>\ninfo@temporex.de<\/p>\n<p>vom stein. agentur f\u00fcr public relations gmbh<br \/>\nSarah Hinderer<br \/>\nHufergasse 13<br \/>\n45239 Essen<br \/>\n0201 \/ 2988120<br \/>\nshi@vom-stein-pr.de<br \/>\nhttp:\/\/www.vom-stein-pr.de<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Da wird Mann schwach &#8211; Neue Kollektion von Designeruhren der Marke DETAMOSO. Besonderes Highlight: Die Ink Paper Watch. Die hochmoderne Technik verbirgt in einem edlen Geh\u00e4use mit dem typischen roten Armband an der Innenseite einen besonderen Clou &#8211; Sie ist ausgestattet mit einer indirekten Displaybeleuchtung, wie sie bereits bei modernen eBook-Readern eingesetzt wird.<\/p>\n","protected":false},"author":89,"featured_media":182275,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11685],"tags":[435],"class_list":["post-104232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mode","tag-default"],"_links":{"self":[{"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/posts\/104232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/comments?post=104232"}],"version-history":[{"count":2,"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/posts\/104232\/revisions"}],"predecessor-version":[{"id":288130,"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/posts\/104232\/revisions\/288130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/media\/182275"}],"wp:attachment":[{"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/media?parent=104232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/categories?post=104232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/tags?post=104232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}