{"id":230049,"date":"2016-05-19T11:09:27","date_gmt":"2016-05-19T11:09:27","guid":{"rendered":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/?p=230049"},"modified":"2017-12-14T13:13:19","modified_gmt":"2017-12-14T11:13:19","slug":"die-richtigen-produktinformationen-zur-richtigen-zeit-shopsystem-mit-marketing-content","status":"publish","type":"post","link":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/die-richtigen-produktinformationen-zur-richtigen-zeit-shopsystem-mit-marketing-content-10230049\/","title":{"rendered":"Die richtigen Produktinformationen zur richtigen Zeit &#8211; Shopsystem mit Marketing Content"},"content":{"rendered":"<p><figure class=\"hammy-responsive alignleft wp-image-230050 \" title=\"Shopsystem mit Marketing-Vorteil\"  data-media=\"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-content\/uploads\/2016\/05\/290196-e1463749089352.jpg\"><noscript><img src=\"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-content\/uploads\/2016\/05\/290196-e1463749089352.jpg\" alt=\"Bild\" title=\"Shopsystem mit Marketing-Vorteil\" width=\"252\" height=\"168\"><\/noscript><\/figure>Shopsystem mit integrierter Marketing Content Plattform<\/p>\n<div>\n<p>demandware und Contentserv bieten kontextbasierten Online Shop<\/p>\n<p>Mit dem Shopsystem von demandware und dem Product Information Management (PIM) von Contentserv haben Online H\u00e4ndler k\u00fcnftig eine Komplettl\u00f6sung f\u00fcr die optimale Customer Experience.<\/p>\n<p><!--more--><\/p>\n<p>Rohrbach\/Ilm 17.05.2016: Contentserv, technologief\u00fchrender Hersteller von Product Information Management und Multichannel Marketing L\u00f6sungen, bietet gemeinsam mit demandware, dem branchenf\u00fchrenden Anbieter von Enterprise-Cloud-Commerce-L\u00f6sungen, eine neuartige Kombi an: Durch die integrierte Marketing Content Plattform von Contentserv sprechen Online H\u00e4ndler ihre Kunden k\u00fcnftig kontextbasiert an und pr\u00e4sentieren ihnen damit die richtigen Produkte zur richtigen Zeit. So erm\u00f6glichen Online H\u00e4ndler ihren Kunden eine unvergessliche Customer Experience.<\/p>\n<p>eCommerce ist auch 2016 Umsatztreiber beim Shopping<\/p>\n<p>Laut der internationalen eCommerce Studie von RetailMeNot vom Januar 2016 nimmt der Umsatz des Onlinehandels in Deutschland um 18,3% weiterhin deutlich zu (auf insgesamt 62,45 Mrd. EUR), w\u00e4hrend das Wachstum des Offlinehandels um fast 2% sinkt. Es bleibt also dabei: Die Kunden von heute und morgen shoppen bequem von unterwegs oder von zu Hause und nutzen daf\u00fcr unterschiedliche Mobile Devices. Immer mehr Anbieter haben diesen Trend erkannt und bieten ihre Produkte daher \u00fcber Online Shops und Online Marktpl\u00e4tze an.<\/p>\n<p>Um in der F\u00fclle von Angeboten hervorzustechen, braucht es daher mehr als einen professionellen Shop und gute Produkte. Erst ein optimales Kauferlebnis trennt die Spreu vom Weizen: Nur wer es schafft, seinen Kunden die richtigen &#8211; und entsprechend tiefen und \u00fcberzeugenden -Produktinformationen zur richtigen Zeit anzubieten und dabei mit emotionalen Erlebnissen und spannenden Geschichten an den digitalen POS (Point of Sale) zu locken, wird langfristig erfolgreich sein und seine Kunden an seine Marke binden.<\/p>\n<p>Doch wie gelingt diese Herausforderung?<\/p>\n<p>Context hei\u00dft das Zauberwort, um Kunden ein positives emotionales Erlebnis zu verschaffen: N\u00e4mlich Angebote, die zum individuellen Bedarf des Kunden und zu seiner jeweiligen Situation passen. Und das konsistent \u00fcber alle Kan\u00e4le hinweg und zu jeder Zeit.<\/p>\n<p>Wie geht das in der Praxis? Die kombinierte L\u00f6sung von Contentserv und demandware bietet Online H\u00e4ndlern und Markenherstellern eine neuartige L\u00f6sung f\u00fcr die kontextbasierte Shopverwaltung: Aufbauend auf der ganzheitlichen eCommerce L\u00f6sung von demandware, die mit ihren innovativen Features bei namhaften Online H\u00e4ndlern wie beispielsweise S.Oliver, Clarins und Adidas im Einsatz ist, sorgt die Marketing Content Plattform von Contentserv daf\u00fcr, dass der gesamte Content f\u00fcr den Shop und alle anderen Kan\u00e4le verwaltet und ausgesteuert wird.<\/p>\n<p>\u00dcber das Product Information Management System (PIM) sowie ein Digital Asset Management System (DAM) wird s\u00e4mtlicher Content wie Bilder, Produkttexte und -attribute oder auch Videos zentral zur Verf\u00fcgung gestellt, verwaltet, automatisiert und f\u00fcr den jeweiligen Kanal optimiert ausgesteuert. So kann hochwertiger Marketingcontent innerhalb k\u00fcrzester Zeit automatisiert in allen Kan\u00e4len ge\u00e4ndert oder getauscht werden und neue Produkte mit H\u00f6chstgeschwindigkeit im Shop platziert werden. Dies gilt insbesondere f\u00fcr Texte und anspruchsvolle Produktdaten, denn so k\u00f6nnen Online H\u00e4ndler die Vorteile des Empfehlungsmarketings voll ausspielen und ihren Kunden jederzeit die f\u00fcr sie passenden Produkte und Texte im demandware Shop pr\u00e4sentieren.<\/p>\n<p>Mehrsprachige Online Shops k\u00f6nnen zudem \u00fcber einen integrierten \u00dcbersetzungsmanager von Contentserv kosten- und zeitsparend mit dem richtigen und vor allem aktuellen Content versorgt werden. Und selbst Printpublikationen wie Kataloge und Angebotsflyer werden mit den umfangreichen Produktdaten via Contentserv beliefert und sind damit neben dem Shop immer topaktuell. So verschmelzen On-, Offline- und Mobile-Kan\u00e4le nahtlos und bieten dem Kunden eine grenzenlose Customer Experience \u00fcber alle Kan\u00e4le.<br \/>\nMehr zu Contentserv ist unter <noindex><a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.contentserv.com\"  >www.contentserv.com<\/a><\/noindex> zu finden. Weitere Informationen zu demandware unter www.demandware.de<\/p>\n<p>\u00dcber CONTENTSERV<br \/>\nContentserv ist f\u00fchrender Anbieter f\u00fcr ganzheitlich integrierte Enterprise Marketing Information Management-L\u00f6sungen zur webbasierten, hoch automatisierten Organisation und Umsetzung von Marketing- und Medienprozessen im Multichannel Marketing. 300.000 User in \u00fcber 89 L\u00e4ndern setzen Contentserv bereits erfolgreich ein. Das LNC Market Performance Wheel bewertet Contentserv als Technologief\u00fchrer f\u00fcr PIM und MAM sowie hervorragende L\u00f6sung f\u00fcr den Mittelstand. Produkt- und Mediendatenmanagement, Publikations- und Planungsprozesse werden mit Contentserv gestrafft und so enorme Kosten- und Zeiteinsparungen erzielt. F\u00fcr schnelle und konsistente Kommunikation in alle Kan\u00e4le &#8211; Online wie Offline.<\/p>\n<p>Firmenkontakt<br \/>\nCONTENTSERV GmbH<br \/>\nPetra Kiermeier<br \/>\nWerner-von-Siemens-Str. 1<br \/>\n85296 Rohrbach \/ Ilm<br \/>\n+49 8442 92 53 870<br \/>\n+49 8442 2044<br \/>\npr@contentserv.com<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"5ASFz8ODmA\"><p><noindex><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.contentserv.com\/\"  >EN_Home<\/a><\/noindex><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.contentserv.com\/embed\/#?secret=5ASFz8ODmA\" data-secret=\"5ASFz8ODmA\" width=\"600\" height=\"338\" title=\"&#8220;EN_Home&#8221; &#8212; Contentserv\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>Pressekontakt<br \/>\nCONTENTSERV GmbH &#8211; ein Unternehmen der CONTENTSERV AG<br \/>\nSandra Skultety<br \/>\nWerner-von-Siemens-Str. 1<br \/>\n85296 Rohrbach \/ Ilm<br \/>\n+49 8442 92 53 870<br \/>\n+49 8442 2044<br \/>\npr@contentserv.com<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"5ASFz8ODmA\"><p><noindex><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.contentserv.com\/\"  >EN_Home<\/a><\/noindex><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.contentserv.com\/embed\/#?secret=5ASFz8ODmA\" data-secret=\"5ASFz8ODmA\" width=\"600\" height=\"338\" title=\"&#8220;EN_Home&#8221; &#8212; Contentserv\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Shopsystem mit integrierter Marketing Content Plattform demandware und Contentserv bieten kontextbasierten Online Shop Mit dem Shopsystem von demandware und dem Product Information Management (PIM) von Contentserv haben Online H\u00e4ndler k\u00fcnftig eine Komplettl\u00f6sung f\u00fcr die optimale Customer Experience.<\/p>\n","protected":false},"author":37,"featured_media":230050,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[423],"tags":[435],"class_list":["post-230049","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shopsoftware-shopsystemhersteller","tag-default"],"_links":{"self":[{"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/posts\/230049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/comments?post=230049"}],"version-history":[{"count":0,"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/posts\/230049\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/media\/230050"}],"wp:attachment":[{"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/media?parent=230049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/categories?post=230049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/tags?post=230049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}