{"id":247484,"date":"2018-01-26T17:04:40","date_gmt":"2018-01-26T15:04:40","guid":{"rendered":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/?p=247484"},"modified":"2018-01-31T21:24:04","modified_gmt":"2018-01-31T19:24:04","slug":"23-internationale-spezialradmesse-am-28-und-29-april","status":"publish","type":"post","link":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/23-internationale-spezialradmesse-am-28-und-29-april-10247484\/","title":{"rendered":"23. Internationale Spezialradmesse am 28. und 29. April"},"content":{"rendered":"<p><span style=\"font-style: italic; padding: 20px 0px 30px 0px;\">Fahrradspa\u00df f\u00fcr Individualisten in Germersheim<\/span><\/p>\n<div style=\"float: left; font-style: italic; font-size: 10px; margin: 5px 10px 5px 0; max-width: 220px; line-height: 1.0em;\">\n<p><figure class=\"hammy-responsive \" title=\"\"  data-media=\"https:\/\/www.pr-gateway.de\/components\/com_gateway\/showimage.php?width=200&height=200&id=335878&uid=1061\"><noscript><img src=\"https:\/\/www.pr-gateway.de\/components\/com_gateway\/showimage.php?width=200&height=200&id=335878&uid=1061\" alt=\"23. Internationale Spezialradmesse am 28. und 29. April\" title=\"\" width=\"\" height=\"\"><\/noscript><\/figure><\/p>\n<div style=\"width: 200px;\">Spezielles aus einer boomenden Fahrrad-Nische: Lieger\u00e4der, Velomobile, Lastenr\u00e4der, E-Bikes etc.<\/div>\n<\/div>\n<p>Den weitesten Weg nach Germersheim haben die neuen Aussteller aus den USA und China: Wenn dann am 28. und 29. April 2018 die Internationale Spezialradmesse ihre Tore \u00f6ffnet, ist in der S\u00fcdpfalz auch nahezu ganz Europa zu Besuch. Das Messegel\u00e4nde ist drinnen wie drau\u00dfen mit rund 120 Ausstellern bereits jetzt so gut wie ausgebucht; rund 10.000 G\u00e4ste werden erwartet.<\/p>\n<p>Der beliebte Branchentreff und Publikumsmagnet lockt mit innovativen Radl\u00f6sungen bereits zum 23. Mal neben Insidern, Erfindern und Technikfreaks auch Reiseradler und Berufspendler nach Germersheim. Die Besucher erwartet wie schon in den Vorjahren das gr\u00f6\u00dfte Angebot an Liegezwei- und -dreir\u00e4dern weltweit. Dar\u00fcber hinaus ist die Spezi das internationale Mekka f\u00fcr Transportl\u00f6sungen: <!--more-->Transport- oder Cargor\u00e4der sowie Anh\u00e4nger sind mit gut zwei Dutzend Ausstellern vertreten. &#8222;Dass ein seit Jahren wachsendes Segment immer noch zulegt, freut uns besonders&#8220;, so Spezi-Veranstalter Hardy Siebecke. &#8222;Das gibt zus\u00e4tzlich Auftrieb und zeigt, wie wichtig vor allem im st\u00e4dtischen Umfeld Transportfahrten per Muskelkraft sind. Nur so k\u00f6nnen wir dem Verkehrskollaps in den Ballungsr\u00e4umen entgegensteuern.&#8220;<\/p>\n<p>Einen dritten Messeschwerpunkt bilden Fahrzeuge mit elektrischem R\u00fcckenwind: Pedelecs, E-Lieger\u00e4der sowie Lastesel mit Motorunterst\u00fctzung gibt es zahlreich zu sehen und auszuprobieren. F\u00fcr Testfahrten steht ein eigener E-Parcours mit Steigungs- und Gef\u00e4llstrecken zur Verf\u00fcgung.<\/p>\n<p>Gemeinsam pr\u00e4sentieren die Aussteller der Spezialradmesse auch 2018 das gesamte Spektrum der innovativen Branche: Lieger\u00e4der, Faltr\u00e4der, Dreir\u00e4der, Tandems, Velomobile, E-Bikes und Pedelecs, Reha-Mobile, Transportr\u00e4der, Klassiker, Fahrradanh\u00e4nger, Ruderr\u00e4der, Familienr\u00e4der, Tretroller, Sesselr\u00e4der und Zubeh\u00f6r rund ums Rad.<\/p>\n<p>Wie jedes Jahr bilden die beiden gro\u00dfen Testparcours das Herz der Spezi. So kann das pers\u00f6nliche Lieblingsrad ausgiebig Probe gefahren werden. Ein spannendes Vortragsprogramm an beiden Tagen sowie der sonnt\u00e4glichen Familientag mit Aktivit\u00e4ten f\u00fcr Kids runden die Spezialradmesse auch 2018 ab.<br \/>\nWeitere Infos unter <noindex><a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.spezialradmesse.de\"  rel=\"nofollow\">www.spezialradmesse.de<\/a><\/noindex> und auf Facebook.<\/p>\n<p>Die Spezialradmesse &#8211; Spezi &#8211; wurde im Jahr 1996 von Haasies Radschlag in Germersheim ins Leben gerufen. Verantwortlich f\u00fcr die Veranstaltung und die Durchf\u00fchrung der Spezialradmesse ist seit 2008 Hardy Siebecke. Die international einzigartige Ausstellung f\u00fcr die Spezialradbranche verzeichnet seit Jahren steigende Aussteller- und Besucherzahlen. Im Jahr 2017 waren \u00fcber 120 Aussteller aus mehr als 17 L\u00e4ndern in Germersheim zu Gast. Sie zeigten das breite Spektrum muskelbetriebener Fortbewegung auf einem, zwei, drei oder vier R\u00e4dern. Rund 10.000 Spezialrad-Fans aus den In- und Ausland kommen jedes Jahr zur Spezi-Zeit in die S\u00fcdpfalz. Zum Rahmenprogramm der Messe geh\u00f6ren interessante Fachvortr\u00e4ge und praktische Vorf\u00fchrungen sowie gro\u00dfe Testparcours f\u00fcr die Besucher.<\/p>\n<p><b>Firmenkontakt<\/b><br \/>\nSpezialradmesse<br \/>\nHardy Siebecke<br \/>\nRobert-Schuman-Str. 42<br \/>\n76726 Germersheim<br \/>\n07275\/5047<br \/>\ninfo@spezialradmesse.de<br \/>\nhttp:\/\/www.spezialradmesse.de<\/p>\n<p><b>Pressekontakt<\/b><br \/>\nMARA Redaktionsb\u00fcro<br \/>\nMarion Raschka<br \/>\nRheinstra\u00dfe 22<br \/>\n76870 Kandel<br \/>\n07275\/5047<br \/>\nmarion.raschka@t-online.de<br \/>\nhttp:\/\/www.mara-redaktion.de<\/p>\n<p><iframe loading=\"lazy\" width=\"350\" height=\"197\" src=\"https:\/\/www.youtube.com\/embed\/D5TzRRduwmM?feature=oembed\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>Fahrradspa\u00df f\u00fcr Individualisten in Germersheim Spezielles aus einer boomenden Fahrrad-Nische: Lieger\u00e4der, Velomobile, Lastenr\u00e4der, E-Bikes etc. Den weitesten Weg nach Germersheim haben die neuen Aussteller aus den USA und China: Wenn dann am 28. und 29. April 2018 die Internationale Spezialradmesse ihre Tore \u00f6ffnet, ist in der S\u00fcdpfalz auch nahezu ganz Europa zu Besuch. Das Messegel\u00e4nde<\/p>\n","protected":false},"author":115,"featured_media":281534,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4671],"tags":[2698,28372,28370,28367,28371,28366,28365,28369,28368,28373,21238],"class_list":["post-247484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport-freizeit","tag-crosstrainer","tag-germersheim","tag-kinderanhaenger","tag-liegerad","tag-reha-raeder","tag-spezialrad","tag-spezialradmesse","tag-transportrad","tag-trike","tag-velomobil","tag-verkehr"],"_links":{"self":[{"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/posts\/247484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/users\/115"}],"replies":[{"embeddable":true,"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/comments?post=247484"}],"version-history":[{"count":0,"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/posts\/247484\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/media\/281534"}],"wp:attachment":[{"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/media?parent=247484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/categories?post=247484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.onlineshops-finden.de\/nachrichten-online-shop\/wp-json\/wp\/v2\/tags?post=247484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}